{"id":73,"count":1,"description":"","link":"http:\/\/www.moonmile.net\/blog\/archives\/category\/dev\/mbed","name":"mbed","slug":"mbed","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"http:\/\/www.moonmile.net\/blog\/wp-json\/wp\/v2\/categories\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.moonmile.net\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.moonmile.net\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/www.moonmile.net\/blog\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"http:\/\/www.moonmile.net\/blog\/wp-json\/wp\/v2\/posts?categories=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}